{"id":977,"date":"2022-12-30T14:38:07","date_gmt":"2022-12-30T13:38:07","guid":{"rendered":"https:\/\/www.cfos-emobility.de\/network\/antworten\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\/"},"modified":"2025-10-23T18:08:34","modified_gmt":"2025-10-23T16:08:34","slug":"vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next","status":"publish","type":"cma_thread","link":"https:\/\/www.cfos-emobility.de\/network\/antworten\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\/","title":{"rendered":"Vaidierung\/Einbindung weiterer Wallboxen wie z.B. Webasto Unite oder Webasto Next?"},"content":{"rendered":"<p>Hallo,<\/p>\n<p>ich hatte wie heute in diesem Beitrag geschrieben, meinen Fronius Wattpiloten mal per OCPP in der cFos Charging Manager eingebunden:https:\/\/www.cfos-emobility.de\/network\/antworten\/charge-manager-fuer-x64-oder-x32\/<\/p>\n<p>L\u00e4uft soweit einwandfrei, nur bietet Fronius leider keine Option eines Fallbacks an &#8211;\u00a0 z.B. auf einen minimalen Ladestrom, oder Deaktivierung der Ladung, sofern die OCPP Verbindung unterbrochen ist.<\/p>\n<p>Wie bek\u00e4me ich denn jetzt z.B. meine Webasto Next oder Unite an den Charging Manager per Modbus eingebunden? &#8211; die entsprechende Modbus Tabelle h\u00e4tte ich.<\/p>\n<p>Die Next kann z.B. entsprechend so konfiguriert werden,\u00a0 dass bei Verlust der Modbus (EMS) Verbindung der Ladestrom begrenzt wird &#8211; siehe Anhang.<\/p>\n<p>Ich benutze das Webasto Charge Connect Backend f\u00fcr Abrechnungszwecke per OCPP und die Kompatibilit\u00e4t mit auch Webasto Ladel\u00f6sungen w\u00e4re sicherlich auch ein sch\u00f6nes Feature!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hallo, ich hatte wie heute in diesem Beitrag geschrieben, meinen Fronius Wattpiloten mal per OCPP in der cFos Charging Manager eingebunden:https:\/\/www.cfos-emobility.de\/network\/antworten\/charge-manager-fuer-x64-oder-x32\/ L\u00e4uft soweit einwandfrei, nur bietet Fronius leider keine Option eines Fallbacks an &#8211;\u00a0 z.B. auf einen minimalen Ladestrom, oder Deaktivierung der Ladung, sofern die OCPP Verbindung unterbrochen ist. Wie bek\u00e4me ich denn jetzt z.B. [&hellip;]<\/p>\n","protected":false},"author":165,"featured_media":0,"template":"","tags":[90],"cma_category":[],"cma_difficulty_level":[],"class_list":["post-977","cma_thread","type-cma_thread","status-publish","hentry","tag-webasto-next-unite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vaidierung\/Einbindung weiterer Wallboxen wie z.B. Webasto Unite oder Webasto Next? - cFos eMobility Network<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vaidierung\/Einbindung weiterer Wallboxen wie z.B. Webasto Unite oder Webasto Next? - cFos eMobility Network\" \/>\n<meta property=\"og:description\" content=\"Hallo, ich hatte wie heute in diesem Beitrag geschrieben, meinen Fronius Wattpiloten mal per OCPP in der cFos Charging Manager eingebunden:https:\/\/www.cfos-emobility.de\/network\/antworten\/charge-manager-fuer-x64-oder-x32\/ L\u00e4uft soweit einwandfrei, nur bietet Fronius leider keine Option eines Fallbacks an &#8211;\u00a0 z.B. auf einen minimalen Ladestrom, oder Deaktivierung der Ladung, sofern die OCPP Verbindung unterbrochen ist. Wie bek\u00e4me ich denn jetzt z.B. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\/\" \/>\n<meta property=\"og:site_name\" content=\"cFos eMobility Network\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T16:08:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cFosEmobility\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\\\/\",\"name\":\"Vaidierung\\\/Einbindung weiterer Wallboxen wie z.B. Webasto Unite oder Webasto Next? - cFos eMobility Network\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\"},\"datePublished\":\"2022-12-30T13:38:07+00:00\",\"dateModified\":\"2025-10-23T16:08:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fragen\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vaidierung\\\/Einbindung weiterer Wallboxen wie z.B. Webasto Unite oder Webasto Next?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"name\":\"cFos eMobility Network\",\"description\":\"Das cFos Power Brain Community Portal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\",\"name\":\"cFos eMobility GmbH\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"width\":221,\"height\":80,\"caption\":\"cFos eMobility GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/cFosEmobility\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vaidierung\/Einbindung weiterer Wallboxen wie z.B. Webasto Unite oder Webasto Next? - cFos eMobility Network","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfos-emobility.de\/network\/antworten\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\/","og_locale":"de_DE","og_type":"article","og_title":"Vaidierung\/Einbindung weiterer Wallboxen wie z.B. Webasto Unite oder Webasto Next? - cFos eMobility Network","og_description":"Hallo, ich hatte wie heute in diesem Beitrag geschrieben, meinen Fronius Wattpiloten mal per OCPP in der cFos Charging Manager eingebunden:https:\/\/www.cfos-emobility.de\/network\/antworten\/charge-manager-fuer-x64-oder-x32\/ L\u00e4uft soweit einwandfrei, nur bietet Fronius leider keine Option eines Fallbacks an &#8211;\u00a0 z.B. auf einen minimalen Ladestrom, oder Deaktivierung der Ladung, sofern die OCPP Verbindung unterbrochen ist. Wie bek\u00e4me ich denn jetzt z.B. [&hellip;]","og_url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\/","og_site_name":"cFos eMobility Network","article_modified_time":"2025-10-23T16:08:34+00:00","twitter_card":"summary_large_image","twitter_site":"@cFosEmobility","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\/","url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\/","name":"Vaidierung\/Einbindung weiterer Wallboxen wie z.B. Webasto Unite oder Webasto Next? - cFos eMobility Network","isPartOf":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#website"},"datePublished":"2022-12-30T13:38:07+00:00","dateModified":"2025-10-23T16:08:34+00:00","breadcrumb":{"@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfos-emobility.de\/network\/antworten\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/vaidierungeinbindung-weiterer-wallboxen-wie-z-b-webasto-unite-oder-webasto-next\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.cfos-emobility.de\/network\/"},{"@type":"ListItem","position":2,"name":"Fragen","item":"https:\/\/www.cfos-emobility.de\/network\/antworten\/"},{"@type":"ListItem","position":3,"name":"Vaidierung\/Einbindung weiterer Wallboxen wie z.B. Webasto Unite oder Webasto Next?"}]},{"@type":"WebSite","@id":"https:\/\/www.cfos-emobility.de\/network\/#website","url":"https:\/\/www.cfos-emobility.de\/network\/","name":"cFos eMobility Network","description":"Das cFos Power Brain Community Portal","publisher":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfos-emobility.de\/network\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cfos-emobility.de\/network\/#organization","name":"cFos eMobility GmbH","url":"https:\/\/www.cfos-emobility.de\/network\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","contentUrl":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","width":221,"height":80,"caption":"cFos eMobility GmbH"},"image":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/cFosEmobility"]}]}},"_links":{"self":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread\/977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread"}],"about":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/types\/cma_thread"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/users\/165"}],"wp:attachment":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/media?parent=977"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/tags?post=977"},{"taxonomy":"cma_category","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_category?post=977"},{"taxonomy":"cma_difficulty_level","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_difficulty_level?post=977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}