{"id":961,"date":"2022-12-22T17:38:57","date_gmt":"2022-12-22T16:38:57","guid":{"rendered":"https:\/\/www.cfos-emobility.de\/network\/?post_type=cma_thread&#038;p=961"},"modified":"2023-06-12T10:08:28","modified_gmt":"2023-06-12T08:08:28","slug":"wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s","status":"publish","type":"cma_thread","link":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\/","title":{"rendered":"Wie integriere ich smarte Steckdosen in den cFos Charging Manager? (Beispiel: Shelly Plug S)"},"content":{"rendered":"<p>Mit der Version 1.16 des cFos Charging Managers lassen sich nun auch eigene Z\u00e4hler und Ger\u00e4te hinzuf\u00fcgen. Besonders n\u00fctzlich und vielseitig einsetzbar ist der Einsatz smarter Steckdosen. Wie l\u00e4sst sich nun beispielsweise ein E-Bike per smarter Steckdose, gesteuert vom cFos Charging Manager und gespeist mit eigenem Solarstrom laden?<\/p>\n<p>Wir erkl\u00e4ren es Ihnen!<\/p>\n<p><strong>Sie haben bereits eine eigene L\u00f6sung f\u00fcr ein anderes Ger\u00e4t? Teilen Sie diese in diese einfach in diesem Thread!<br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 12px;\"><em>Hinweis: Wir haben uns f\u00fcr ein Produkt von Shelly entschieden, da die Produkte sehr gel\u00e4ufig und \u00fcberall erh\u00e4ltlich sind. Die folgende Anleitung dient der Veranschaulichung, wie sich eine smarte Steckdose hinzuf\u00fcgen l\u00e4sst. Die Firmen Shelly und cFos eMobility haben weder eine bezahlte noch unbezahlte Werberpartnerschaft vereinbart.<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit der Version 1.16 des cFos Charging Managers lassen sich nun auch eigene Z\u00e4hler und Ger\u00e4te hinzuf\u00fcgen. Besonders n\u00fctzlich und vielseitig einsetzbar ist der Einsatz smarter Steckdosen. Wie l\u00e4sst sich nun beispielsweise ein E-Bike per smarter Steckdose, gesteuert vom cFos Charging Manager und gespeist mit eigenem Solarstrom laden? Wir erkl\u00e4ren es Ihnen! Sie haben bereits [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","tags":[],"cma_category":[7],"cma_difficulty_level":[],"class_list":["post-961","cma_thread","type-cma_thread","status-publish","hentry","cma_category-cfos-charging-manager"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie integriere ich smarte Steckdosen in den cFos Charging Manager? (Beispiel: Shelly Plug S) - cFos eMobility Network<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie integriere ich smarte Steckdosen in den cFos Charging Manager? (Beispiel: Shelly Plug S) - cFos eMobility Network\" \/>\n<meta property=\"og:description\" content=\"Mit der Version 1.16 des cFos Charging Managers lassen sich nun auch eigene Z\u00e4hler und Ger\u00e4te hinzuf\u00fcgen. Besonders n\u00fctzlich und vielseitig einsetzbar ist der Einsatz smarter Steckdosen. Wie l\u00e4sst sich nun beispielsweise ein E-Bike per smarter Steckdose, gesteuert vom cFos Charging Manager und gespeist mit eigenem Solarstrom laden? Wir erkl\u00e4ren es Ihnen! Sie haben bereits [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\/\" \/>\n<meta property=\"og:site_name\" content=\"cFos eMobility Network\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-12T08:08:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cFosEmobility\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\\\/\",\"name\":\"Wie integriere ich smarte Steckdosen in den cFos Charging Manager? (Beispiel: Shelly Plug S) - cFos eMobility Network\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\"},\"datePublished\":\"2022-12-22T16:38:57+00:00\",\"dateModified\":\"2023-06-12T08:08:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fragen\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wie integriere ich smarte Steckdosen in den cFos Charging Manager? (Beispiel: Shelly Plug S)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"name\":\"cFos eMobility Network\",\"description\":\"Das cFos Power Brain Community Portal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\",\"name\":\"cFos eMobility GmbH\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"width\":221,\"height\":80,\"caption\":\"cFos eMobility GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/cFosEmobility\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie integriere ich smarte Steckdosen in den cFos Charging Manager? (Beispiel: Shelly Plug S) - cFos eMobility Network","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\/","og_locale":"de_DE","og_type":"article","og_title":"Wie integriere ich smarte Steckdosen in den cFos Charging Manager? (Beispiel: Shelly Plug S) - cFos eMobility Network","og_description":"Mit der Version 1.16 des cFos Charging Managers lassen sich nun auch eigene Z\u00e4hler und Ger\u00e4te hinzuf\u00fcgen. Besonders n\u00fctzlich und vielseitig einsetzbar ist der Einsatz smarter Steckdosen. Wie l\u00e4sst sich nun beispielsweise ein E-Bike per smarter Steckdose, gesteuert vom cFos Charging Manager und gespeist mit eigenem Solarstrom laden? Wir erkl\u00e4ren es Ihnen! Sie haben bereits [&hellip;]","og_url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\/","og_site_name":"cFos eMobility Network","article_modified_time":"2023-06-12T08:08:28+00:00","twitter_card":"summary_large_image","twitter_site":"@cFosEmobility","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\/","url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\/","name":"Wie integriere ich smarte Steckdosen in den cFos Charging Manager? (Beispiel: Shelly Plug S) - cFos eMobility Network","isPartOf":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#website"},"datePublished":"2022-12-22T16:38:57+00:00","dateModified":"2023-06-12T08:08:28+00:00","breadcrumb":{"@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-integriere-ich-smarte-steckdosen-in-den-cfos-charging-manager-beispiel-shelly-plug-s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.cfos-emobility.de\/network\/"},{"@type":"ListItem","position":2,"name":"Fragen","item":"https:\/\/www.cfos-emobility.de\/network\/antworten\/"},{"@type":"ListItem","position":3,"name":"Wie integriere ich smarte Steckdosen in den cFos Charging Manager? (Beispiel: Shelly Plug S)"}]},{"@type":"WebSite","@id":"https:\/\/www.cfos-emobility.de\/network\/#website","url":"https:\/\/www.cfos-emobility.de\/network\/","name":"cFos eMobility Network","description":"Das cFos Power Brain Community Portal","publisher":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfos-emobility.de\/network\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cfos-emobility.de\/network\/#organization","name":"cFos eMobility GmbH","url":"https:\/\/www.cfos-emobility.de\/network\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","contentUrl":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","width":221,"height":80,"caption":"cFos eMobility GmbH"},"image":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/cFosEmobility"]}]}},"_links":{"self":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread\/961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread"}],"about":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/types\/cma_thread"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/media?parent=961"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/tags?post=961"},{"taxonomy":"cma_category","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_category?post=961"},{"taxonomy":"cma_difficulty_level","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_difficulty_level?post=961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}