{"id":924,"date":"2022-12-07T16:13:30","date_gmt":"2022-12-07T15:13:30","guid":{"rendered":"https:\/\/www.cfos-emobility.de\/network\/antworten\/quasi-ueberschussladen\/"},"modified":"2023-06-07T09:42:15","modified_gmt":"2023-06-07T07:42:15","slug":"quasi-ueberschussladen","status":"publish","type":"cma_thread","link":"https:\/\/www.cfos-emobility.de\/network\/antworten\/quasi-ueberschussladen\/","title":{"rendered":"Quasi \u00dcberschussladen???"},"content":{"rendered":"<p>Wir bekommen im Januar \/ Februar eine ca. 6KVP PV-Anlage.<br \/>\nDer Wechselrichter (mal sehen was lieferbar ist) kann wahrscheinlich nicht mit der CFOS Wallbox per IP kommunizieren.<br \/>\nMacht aber nichts.<br \/>\nMeine Idee ist es das eAuto zu laden, wenn die Sonne scheint (geht, weil wir 2 eAutos haben).<br \/>\n6 KVP bei nicht optimaler Richtung (Ost \/ West) bringen ja eh max. 4,5 KVP.<br \/>\nDann br\u00e4uchte ich nicht auf 1 Phasig umstellen usw.<\/p>\n<p>W\u00e4re das eine gute und einfache L\u00f6sung oder gibt es bessere Ideen.<\/p>\n<p>Danke und Gr\u00fc\u00dfe<br \/>\n&#8230; J\u00f6rg<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir bekommen im Januar \/ Februar eine ca. 6KVP PV-Anlage. Der Wechselrichter (mal sehen was lieferbar ist) kann wahrscheinlich nicht mit der CFOS Wallbox per IP kommunizieren. Macht aber nichts. Meine Idee ist es das eAuto zu laden, wenn die Sonne scheint (geht, weil wir 2 eAutos haben). 6 KVP bei nicht optimaler Richtung (Ost [&hellip;]<\/p>\n","protected":false},"author":158,"featured_media":0,"template":"","tags":[48,37],"cma_category":[],"cma_difficulty_level":[],"class_list":["post-924","cma_thread","type-cma_thread","status-publish","hentry","tag-pv-ueberschuss","tag-ueberschussladen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quasi \u00dcberschussladen??? - cFos eMobility Network<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/quasi-ueberschussladen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quasi \u00dcberschussladen??? - cFos eMobility Network\" \/>\n<meta property=\"og:description\" content=\"Wir bekommen im Januar \/ Februar eine ca. 6KVP PV-Anlage. Der Wechselrichter (mal sehen was lieferbar ist) kann wahrscheinlich nicht mit der CFOS Wallbox per IP kommunizieren. Macht aber nichts. Meine Idee ist es das eAuto zu laden, wenn die Sonne scheint (geht, weil wir 2 eAutos haben). 6 KVP bei nicht optimaler Richtung (Ost [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/quasi-ueberschussladen\/\" \/>\n<meta property=\"og:site_name\" content=\"cFos eMobility Network\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-07T07:42:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cFosEmobility\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/quasi-ueberschussladen\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/quasi-ueberschussladen\\\/\",\"name\":\"Quasi \u00dcberschussladen??? - cFos eMobility Network\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\"},\"datePublished\":\"2022-12-07T15:13:30+00:00\",\"dateModified\":\"2023-06-07T07:42:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/quasi-ueberschussladen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/quasi-ueberschussladen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/quasi-ueberschussladen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fragen\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quasi \u00dcberschussladen???\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"name\":\"cFos eMobility Network\",\"description\":\"Das cFos Power Brain Community Portal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\",\"name\":\"cFos eMobility GmbH\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"width\":221,\"height\":80,\"caption\":\"cFos eMobility GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/cFosEmobility\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quasi \u00dcberschussladen??? - cFos eMobility Network","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfos-emobility.de\/network\/antworten\/quasi-ueberschussladen\/","og_locale":"de_DE","og_type":"article","og_title":"Quasi \u00dcberschussladen??? - cFos eMobility Network","og_description":"Wir bekommen im Januar \/ Februar eine ca. 6KVP PV-Anlage. Der Wechselrichter (mal sehen was lieferbar ist) kann wahrscheinlich nicht mit der CFOS Wallbox per IP kommunizieren. Macht aber nichts. Meine Idee ist es das eAuto zu laden, wenn die Sonne scheint (geht, weil wir 2 eAutos haben). 6 KVP bei nicht optimaler Richtung (Ost [&hellip;]","og_url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/quasi-ueberschussladen\/","og_site_name":"cFos eMobility Network","article_modified_time":"2023-06-07T07:42:15+00:00","twitter_card":"summary_large_image","twitter_site":"@cFosEmobility","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/quasi-ueberschussladen\/","url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/quasi-ueberschussladen\/","name":"Quasi \u00dcberschussladen??? - cFos eMobility Network","isPartOf":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#website"},"datePublished":"2022-12-07T15:13:30+00:00","dateModified":"2023-06-07T07:42:15+00:00","breadcrumb":{"@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/quasi-ueberschussladen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfos-emobility.de\/network\/antworten\/quasi-ueberschussladen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/quasi-ueberschussladen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.cfos-emobility.de\/network\/"},{"@type":"ListItem","position":2,"name":"Fragen","item":"https:\/\/www.cfos-emobility.de\/network\/antworten\/"},{"@type":"ListItem","position":3,"name":"Quasi \u00dcberschussladen???"}]},{"@type":"WebSite","@id":"https:\/\/www.cfos-emobility.de\/network\/#website","url":"https:\/\/www.cfos-emobility.de\/network\/","name":"cFos eMobility Network","description":"Das cFos Power Brain Community Portal","publisher":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfos-emobility.de\/network\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cfos-emobility.de\/network\/#organization","name":"cFos eMobility GmbH","url":"https:\/\/www.cfos-emobility.de\/network\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","contentUrl":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","width":221,"height":80,"caption":"cFos eMobility GmbH"},"image":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/cFosEmobility"]}]}},"_links":{"self":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread\/924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread"}],"about":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/types\/cma_thread"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/users\/158"}],"wp:attachment":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/media?parent=924"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/tags?post=924"},{"taxonomy":"cma_category","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_category?post=924"},{"taxonomy":"cma_difficulty_level","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_difficulty_level?post=924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}