{"id":6337,"date":"2025-08-23T10:33:04","date_gmt":"2025-08-23T08:33:04","guid":{"rendered":"https:\/\/www.cfos-emobility.de\/network\/antworten\/analyse-debug-log-doku-2\/"},"modified":"2025-08-29T17:10:02","modified_gmt":"2025-08-29T15:10:02","slug":"analyse-debug-log-doku-2","status":"publish","type":"cma_thread","link":"https:\/\/www.cfos-emobility.de\/network\/antworten\/analyse-debug-log-doku-2\/","title":{"rendered":"Analyse Debug Log &#8211; Doku"},"content":{"rendered":"<p>Hallo zusammen,<\/p>\n<p>zweiter Versuch&#8230;der Hinweis, dass ein Tag notwendig ist, w\u00e4re sch\u00f6n, bevor die Frage nach &#8222;Absenden&#8220; im Nirwana verschwindet&#8230; \ud83d\ude09<\/p>\n<p>Ist es m\u00f6glich, die Werte des Debugging dokumentarisch zu ergr\u00fcnden? Ich habe n\u00e4mlich das Problem, dass der Manager die Regeln nach Gutd\u00fcnken (an einem Tag l\u00e4uft&#8217;s, am n\u00e4chsten nicht mehr) irgendwie nicht so durchl\u00e4uft, wie es lt. Doku sein sollte. Zum einen scheint er trotz &#8222;beenden&#8220; alle Unterregeln ohne &#8222;PV-\u00dcberschuss&#8220; trotzdem abzuarbeiten. Zum anderen scheint er zwar einen Wert einzustellen (v=&#8230;.), aber es flie\u00dft trotz allem kein Strom. Stellenweise szellt er lt. GUI sogar auf &#8222;Aus&#8220;, obwohl kein &#8222;Laden beenden\/starten&#8220; angehakt ist.<\/p>\n<p>Hier mal ein Log-Auszug:<\/p>\n<pre class=\"card-body bg-dark text-white overflow-auto mb-0\">\r\n2025-08-23T10:22:15.618 LB M meter_dem4b M3 4 0\/0\/0,0,0 A E1\r\n2025-08-23T10:22:15.620 LB E evse_powerbrain E1 0\/1 0\/0\/0,0,0 2 0\r\n2025-08-23T10:22:15.621 LB M meter_shelly_pro_3em_http_json M4 3 -1913\/-1813\/-1442,-3805,-3069\r\n2025-08-23T10:22:15.622 LB Ms 0 true T-1913\/-1813\/-1442,-3805,-3069 C0\/0\/0,0,0 P0\/0\/0,0,0 E0\/0\/0,0,0 SH0\/0\/0,0,0 SA0\/0\/0,0,0\r\n2025-08-23T10:22:15.624 LB MS 0 G-1913\/-1813\/-1442,-3805,-3069 SP1913\/1813\/1442,3805,3069 PW-1913\/-1813\/-1442,-3805,-3069 CE0\/0\/0,0,0 EP45383\/45283\/64442,66805,66069\r\n2025-08-23T10:22:15.626 CR rset: \r\n2025-08-23T10:22:15.627 CR rset: \r\n2025-08-23T10:22:15.628 CR 1201\/0 SP 5000 true\/true: 10 v=7882\r\n2025-08-23T10:22:15.629 CR eval 4 E1 0 0 2\r\n2025-08-23T10:22:15.631 CR rfid  7882\r\n2025-08-23T10:22:15.632 CR E1 rule applied 7882\r\n2025-08-23T10:22:15.633 LB add_spcur 7882\r\n2025-08-23T10:22:15.635 LB SPS3-1 E1 5000 5000 true\/false\/false\r\n2025-08-23T10:22:15.636 CR rset: \r\n2025-08-23T10:22:15.637 CR rset: \r\n2025-08-23T10:22:15.638 LB add_cur 0 64442\r\n2025-08-23T10:22:15.639 LB add_cur 1 66805\r\n2025-08-23T10:22:15.640 LB add_cur 2 66069\r\n2025-08-23T10:22:15.642 LB set_cur E1 5000 0 5000 5000 5000\r\n2025-08-23T10:22:18.668 LB M meter_dem4b M3 4 0\/0\/0,0,0 A E1\r\n2025-08-23T10:22:18.670 LB E evse_powerbrain E1 0\/1 0\/0\/0,0,0 2 0\r\n2025-08-23T10:22:18.671 LB M meter_shelly_pro_3em_http_json M4 3 -1894\/-1761\/-1343,-3813,-3079\r\n2025-08-23T10:22:18.672 LB Ms 0 true T-1894\/-1761\/-1343,-3813,-3079 C0\/0\/0,0,0 P0\/0\/0,0,0 E0\/0\/0,0,0 SH0\/0\/0,0,0 SA0\/0\/0,0,0\r\n2025-08-23T10:22:18.674 LB MS 0 G-1894\/-1761\/-1343,-3813,-3079 SP1894\/1761\/1343,3813,3079 PW-1894\/-1761\/-1343,-3813,-3079 CE0\/0\/0,0,0 EP45364\/45231\/64343,66813,66079\r\n2025-08-23T10:22:18.676 CR rset: \r\n2025-08-23T10:22:18.677 CR rset: \r\n2025-08-23T10:22:18.678 CR 1201\/0 SP 5000 true\/true: 10 v=7656\r\n2025-08-23T10:22:18.679 CR eval 4 E1 0 0 2\r\n2025-08-23T10:22:18.680 CR rfid  7656\r\n2025-08-23T10:22:18.681 CR E1 rule applied 7656\r\n2025-08-23T10:22:18.683 LB add_spcur 7656\r\n2025-08-23T10:22:18.684 LB SPS3-1 E1 5000 5000 true\/false\/false\r\n2025-08-23T10:22:18.686 CR rset: \r\n2025-08-23T10:22:18.687 CR rset: \r\n2025-08-23T10:22:18.687 LB add_cur 0 64343\r\n2025-08-23T10:22:18.689 LB add_cur 1 66813\r\n2025-08-23T10:22:18.690 LB add_cur 2 66079\r\n2025-08-23T10:22:18.692 LB set_cur E1 5000 0 5000 5000 5000<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Hallo zusammen, zweiter Versuch&#8230;der Hinweis, dass ein Tag notwendig ist, w\u00e4re sch\u00f6n, bevor die Frage nach &#8222;Absenden&#8220; im Nirwana verschwindet&#8230; \ud83d\ude09 Ist es m\u00f6glich, die Werte des Debugging dokumentarisch zu ergr\u00fcnden? Ich habe n\u00e4mlich das Problem, dass der Manager die Regeln nach Gutd\u00fcnken (an einem Tag l\u00e4uft&#8217;s, am n\u00e4chsten nicht mehr) irgendwie nicht so durchl\u00e4uft, [&hellip;]<\/p>\n","protected":false},"author":710,"featured_media":0,"template":"","tags":[500,499,498,5],"cma_category":[2],"cma_difficulty_level":[],"class_list":["post-6337","cma_thread","type-cma_thread","status-publish","hentry","tag-analyse","tag-debug","tag-manager","tag-wallbox","cma_category-cfos-emobility"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Analyse Debug Log - Doku - cFos eMobility Network<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/analyse-debug-log-doku-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Analyse Debug Log - Doku - cFos eMobility Network\" \/>\n<meta property=\"og:description\" content=\"Hallo zusammen, zweiter Versuch&#8230;der Hinweis, dass ein Tag notwendig ist, w\u00e4re sch\u00f6n, bevor die Frage nach &#8222;Absenden&#8220; im Nirwana verschwindet&#8230; \ud83d\ude09 Ist es m\u00f6glich, die Werte des Debugging dokumentarisch zu ergr\u00fcnden? Ich habe n\u00e4mlich das Problem, dass der Manager die Regeln nach Gutd\u00fcnken (an einem Tag l\u00e4uft&#8217;s, am n\u00e4chsten nicht mehr) irgendwie nicht so durchl\u00e4uft, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/analyse-debug-log-doku-2\/\" \/>\n<meta property=\"og:site_name\" content=\"cFos eMobility Network\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T15:10:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cFosEmobility\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/analyse-debug-log-doku-2\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/analyse-debug-log-doku-2\\\/\",\"name\":\"Analyse Debug Log - Doku - cFos eMobility Network\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\"},\"datePublished\":\"2025-08-23T08:33:04+00:00\",\"dateModified\":\"2025-08-29T15:10:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/analyse-debug-log-doku-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/analyse-debug-log-doku-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/analyse-debug-log-doku-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fragen\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Analyse Debug Log &#8211; Doku\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"name\":\"cFos eMobility Network\",\"description\":\"Das cFos Power Brain Community Portal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\",\"name\":\"cFos eMobility GmbH\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"width\":221,\"height\":80,\"caption\":\"cFos eMobility GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/cFosEmobility\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Analyse Debug Log - Doku - cFos eMobility Network","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfos-emobility.de\/network\/antworten\/analyse-debug-log-doku-2\/","og_locale":"de_DE","og_type":"article","og_title":"Analyse Debug Log - Doku - cFos eMobility Network","og_description":"Hallo zusammen, zweiter Versuch&#8230;der Hinweis, dass ein Tag notwendig ist, w\u00e4re sch\u00f6n, bevor die Frage nach &#8222;Absenden&#8220; im Nirwana verschwindet&#8230; \ud83d\ude09 Ist es m\u00f6glich, die Werte des Debugging dokumentarisch zu ergr\u00fcnden? Ich habe n\u00e4mlich das Problem, dass der Manager die Regeln nach Gutd\u00fcnken (an einem Tag l\u00e4uft&#8217;s, am n\u00e4chsten nicht mehr) irgendwie nicht so durchl\u00e4uft, [&hellip;]","og_url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/analyse-debug-log-doku-2\/","og_site_name":"cFos eMobility Network","article_modified_time":"2025-08-29T15:10:02+00:00","twitter_card":"summary_large_image","twitter_site":"@cFosEmobility","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/analyse-debug-log-doku-2\/","url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/analyse-debug-log-doku-2\/","name":"Analyse Debug Log - Doku - cFos eMobility Network","isPartOf":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#website"},"datePublished":"2025-08-23T08:33:04+00:00","dateModified":"2025-08-29T15:10:02+00:00","breadcrumb":{"@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/analyse-debug-log-doku-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfos-emobility.de\/network\/antworten\/analyse-debug-log-doku-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/analyse-debug-log-doku-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.cfos-emobility.de\/network\/"},{"@type":"ListItem","position":2,"name":"Fragen","item":"https:\/\/www.cfos-emobility.de\/network\/antworten\/"},{"@type":"ListItem","position":3,"name":"Analyse Debug Log &#8211; Doku"}]},{"@type":"WebSite","@id":"https:\/\/www.cfos-emobility.de\/network\/#website","url":"https:\/\/www.cfos-emobility.de\/network\/","name":"cFos eMobility Network","description":"Das cFos Power Brain Community Portal","publisher":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfos-emobility.de\/network\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cfos-emobility.de\/network\/#organization","name":"cFos eMobility GmbH","url":"https:\/\/www.cfos-emobility.de\/network\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","contentUrl":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","width":221,"height":80,"caption":"cFos eMobility GmbH"},"image":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/cFosEmobility"]}]}},"_links":{"self":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread\/6337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread"}],"about":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/types\/cma_thread"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/users\/710"}],"wp:attachment":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/media?parent=6337"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/tags?post=6337"},{"taxonomy":"cma_category","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_category?post=6337"},{"taxonomy":"cma_difficulty_level","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_difficulty_level?post=6337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}