{"id":4842,"date":"2024-12-21T08:59:37","date_gmt":"2024-12-21T07:59:37","guid":{"rendered":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-komme-ich-an-das-ladelog-per-api-ran\/"},"modified":"2025-03-02T14:26:45","modified_gmt":"2025-03-02T13:26:45","slug":"wie-komme-ich-an-das-ladelog-per-api-ran","status":"publish","type":"cma_thread","link":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-komme-ich-an-das-ladelog-per-api-ran\/","title":{"rendered":"wie komme ich an das Ladelog per API ran?"},"content":{"rendered":"<p>Bisher f\u00fchre ich mit einem Google Sheet ein manuelles Ladelog f\u00fcr unsere E-Auto. In dem ich<br \/>\nKM-Stand, Datum, Start, Ende, Ort, Dauer, kWH, kW, %Delta, RR km, Preis, EUR\/kWh, EUR\/100km und den Ladeservice eintrage. Damit kann ich dann auch Summen und Durchschnittswerte \u00fcber verschiedene Anbieter berechnen. Die \u00dcbernahme der Daten aus dem cFOS ist f\u00fcr mich im Moment schwierig, weil die Anzeige im Webui keine Tabellarische Form hat. Ein API Zugriff w\u00e4re f\u00fcr mich sinnvoll oder der direkte Zugang zu den Rohdaten\/der Datenbank (wenn es denn eine gibt). Bisher habe ich nur eine http API Beschreibung https:\/\/www.cfos-emobility.de\/de\/cfos-power-brain\/http-api.htm<\/p>\n<p>entdeckt die f\u00fcr meine Zwecke viel zu low level \/ technisch ist und eine M\u00f6glichkeit die Z\u00e4hlerdaten zu sichern dann bekomme ich ein meterdata.archive ohne weiter Erl\u00e4uterung was ich damit anfangen kann. Hier im Forum habe ich zu dem Thema bisher auch nichts gefunden.<\/p>\n<p><strong>Wie kann ich hier weiter kommen?<br \/>\nWelche Daten sind verf\u00fcgbar?<br \/>\nWie k\u00f6nnen diese per API \/ Software abgerufen werden?<\/p>\n<p><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bisher f\u00fchre ich mit einem Google Sheet ein manuelles Ladelog f\u00fcr unsere E-Auto. In dem ich KM-Stand, Datum, Start, Ende, Ort, Dauer, kWH, kW, %Delta, RR km, Preis, EUR\/kWh, EUR\/100km und den Ladeservice eintrage. Damit kann ich dann auch Summen und Durchschnittswerte \u00fcber verschiedene Anbieter berechnen. Die \u00dcbernahme der Daten aus dem cFOS ist f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":546,"featured_media":0,"template":"","tags":[5],"cma_category":[],"cma_difficulty_level":[],"class_list":["post-4842","cma_thread","type-cma_thread","status-publish","hentry","tag-wallbox"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>wie komme ich an das Ladelog per API ran? - cFos eMobility Network<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-komme-ich-an-das-ladelog-per-api-ran\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"wie komme ich an das Ladelog per API ran? - cFos eMobility Network\" \/>\n<meta property=\"og:description\" content=\"Bisher f\u00fchre ich mit einem Google Sheet ein manuelles Ladelog f\u00fcr unsere E-Auto. In dem ich KM-Stand, Datum, Start, Ende, Ort, Dauer, kWH, kW, %Delta, RR km, Preis, EUR\/kWh, EUR\/100km und den Ladeservice eintrage. Damit kann ich dann auch Summen und Durchschnittswerte \u00fcber verschiedene Anbieter berechnen. Die \u00dcbernahme der Daten aus dem cFOS ist f\u00fcr [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-komme-ich-an-das-ladelog-per-api-ran\/\" \/>\n<meta property=\"og:site_name\" content=\"cFos eMobility Network\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-02T13:26:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cFosEmobility\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/wie-komme-ich-an-das-ladelog-per-api-ran\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/wie-komme-ich-an-das-ladelog-per-api-ran\\\/\",\"name\":\"wie komme ich an das Ladelog per API ran? - cFos eMobility Network\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\"},\"datePublished\":\"2024-12-21T07:59:37+00:00\",\"dateModified\":\"2025-03-02T13:26:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/wie-komme-ich-an-das-ladelog-per-api-ran\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/wie-komme-ich-an-das-ladelog-per-api-ran\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/wie-komme-ich-an-das-ladelog-per-api-ran\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fragen\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"wie komme ich an das Ladelog per API ran?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"name\":\"cFos eMobility Network\",\"description\":\"Das cFos Power Brain Community Portal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\",\"name\":\"cFos eMobility GmbH\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"width\":221,\"height\":80,\"caption\":\"cFos eMobility GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/cFosEmobility\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"wie komme ich an das Ladelog per API ran? - cFos eMobility Network","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-komme-ich-an-das-ladelog-per-api-ran\/","og_locale":"de_DE","og_type":"article","og_title":"wie komme ich an das Ladelog per API ran? - cFos eMobility Network","og_description":"Bisher f\u00fchre ich mit einem Google Sheet ein manuelles Ladelog f\u00fcr unsere E-Auto. In dem ich KM-Stand, Datum, Start, Ende, Ort, Dauer, kWH, kW, %Delta, RR km, Preis, EUR\/kWh, EUR\/100km und den Ladeservice eintrage. Damit kann ich dann auch Summen und Durchschnittswerte \u00fcber verschiedene Anbieter berechnen. Die \u00dcbernahme der Daten aus dem cFOS ist f\u00fcr [&hellip;]","og_url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-komme-ich-an-das-ladelog-per-api-ran\/","og_site_name":"cFos eMobility Network","article_modified_time":"2025-03-02T13:26:45+00:00","twitter_card":"summary_large_image","twitter_site":"@cFosEmobility","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-komme-ich-an-das-ladelog-per-api-ran\/","url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-komme-ich-an-das-ladelog-per-api-ran\/","name":"wie komme ich an das Ladelog per API ran? - cFos eMobility Network","isPartOf":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#website"},"datePublished":"2024-12-21T07:59:37+00:00","dateModified":"2025-03-02T13:26:45+00:00","breadcrumb":{"@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-komme-ich-an-das-ladelog-per-api-ran\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-komme-ich-an-das-ladelog-per-api-ran\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/wie-komme-ich-an-das-ladelog-per-api-ran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.cfos-emobility.de\/network\/"},{"@type":"ListItem","position":2,"name":"Fragen","item":"https:\/\/www.cfos-emobility.de\/network\/antworten\/"},{"@type":"ListItem","position":3,"name":"wie komme ich an das Ladelog per API ran?"}]},{"@type":"WebSite","@id":"https:\/\/www.cfos-emobility.de\/network\/#website","url":"https:\/\/www.cfos-emobility.de\/network\/","name":"cFos eMobility Network","description":"Das cFos Power Brain Community Portal","publisher":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfos-emobility.de\/network\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cfos-emobility.de\/network\/#organization","name":"cFos eMobility GmbH","url":"https:\/\/www.cfos-emobility.de\/network\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","contentUrl":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","width":221,"height":80,"caption":"cFos eMobility GmbH"},"image":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/cFosEmobility"]}]}},"_links":{"self":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread\/4842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread"}],"about":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/types\/cma_thread"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/users\/546"}],"wp:attachment":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/media?parent=4842"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/tags?post=4842"},{"taxonomy":"cma_category","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_category?post=4842"},{"taxonomy":"cma_difficulty_level","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_difficulty_level?post=4842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}