{"id":397,"date":"2022-02-22T10:34:04","date_gmt":"2022-02-22T09:34:04","guid":{"rendered":"https:\/\/www.cfos-emobility.de\/network\/antworten\/zaehler-or-we-517-mit-universal-modbus-gateway\/"},"modified":"2022-02-25T13:38:31","modified_gmt":"2022-02-25T12:38:31","slug":"zaehler-or-we-517-mit-universal-modbus-gateway","status":"publish","type":"cma_thread","link":"https:\/\/www.cfos-emobility.de\/network\/antworten\/zaehler-or-we-517-mit-universal-modbus-gateway\/","title":{"rendered":"Z\u00e4hler OR-WE-517 mit Universal Modbus Gateway"},"content":{"rendered":"<p>Hallo,<\/p>\n<p>nach Installation meiner PV-Anlage habe ich mir im Z\u00e4hlerschrank einen Z\u00e4hler Orno OR-WE-517 zusammen mit dem Universal Modbus Gateway (https:\/\/www.ebay.de\/itm\/154058806297\/) einbauen lassen.<\/p>\n<p>Nun w\u00fcrde ich gerne den Z\u00e4hler als Netzbezugsz\u00e4hler in der Wallbox einrichten, bekomme das aber nicht hin bzw. es gibt nur den Z\u00e4hler OR-WE-516. Damit bekomme ich aber keine Werte bzw. falsche Werte angezeigt.<\/p>\n<p>Hat jemand eine Idee?<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hallo, nach Installation meiner PV-Anlage habe ich mir im Z\u00e4hlerschrank einen Z\u00e4hler Orno OR-WE-517 zusammen mit dem Universal Modbus Gateway (https:\/\/www.ebay.de\/itm\/154058806297\/) einbauen lassen. Nun w\u00fcrde ich gerne den Z\u00e4hler als Netzbezugsz\u00e4hler in der Wallbox einrichten, bekomme das aber nicht hin bzw. es gibt nur den Z\u00e4hler OR-WE-516. Damit bekomme ich aber keine Werte bzw. falsche [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"template":"","tags":[33,32],"cma_category":[],"cma_difficulty_level":[],"class_list":["post-397","cma_thread","type-cma_thread","status-publish","hentry","tag-modbus","tag-zaehler"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Z\u00e4hler OR-WE-517 mit Universal Modbus Gateway - cFos eMobility Network<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/zaehler-or-we-517-mit-universal-modbus-gateway\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Z\u00e4hler OR-WE-517 mit Universal Modbus Gateway - cFos eMobility Network\" \/>\n<meta property=\"og:description\" content=\"Hallo, nach Installation meiner PV-Anlage habe ich mir im Z\u00e4hlerschrank einen Z\u00e4hler Orno OR-WE-517 zusammen mit dem Universal Modbus Gateway (https:\/\/www.ebay.de\/itm\/154058806297\/) einbauen lassen. Nun w\u00fcrde ich gerne den Z\u00e4hler als Netzbezugsz\u00e4hler in der Wallbox einrichten, bekomme das aber nicht hin bzw. es gibt nur den Z\u00e4hler OR-WE-516. Damit bekomme ich aber keine Werte bzw. falsche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/zaehler-or-we-517-mit-universal-modbus-gateway\/\" \/>\n<meta property=\"og:site_name\" content=\"cFos eMobility Network\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-25T12:38:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cFosEmobility\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/zaehler-or-we-517-mit-universal-modbus-gateway\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/zaehler-or-we-517-mit-universal-modbus-gateway\\\/\",\"name\":\"Z\u00e4hler OR-WE-517 mit Universal Modbus Gateway - cFos eMobility Network\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\"},\"datePublished\":\"2022-02-22T09:34:04+00:00\",\"dateModified\":\"2022-02-25T12:38:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/zaehler-or-we-517-mit-universal-modbus-gateway\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/zaehler-or-we-517-mit-universal-modbus-gateway\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/zaehler-or-we-517-mit-universal-modbus-gateway\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fragen\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Z\u00e4hler OR-WE-517 mit Universal Modbus Gateway\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"name\":\"cFos eMobility Network\",\"description\":\"Das cFos Power Brain Community Portal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\",\"name\":\"cFos eMobility GmbH\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"width\":221,\"height\":80,\"caption\":\"cFos eMobility GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/cFosEmobility\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Z\u00e4hler OR-WE-517 mit Universal Modbus Gateway - cFos eMobility Network","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfos-emobility.de\/network\/antworten\/zaehler-or-we-517-mit-universal-modbus-gateway\/","og_locale":"de_DE","og_type":"article","og_title":"Z\u00e4hler OR-WE-517 mit Universal Modbus Gateway - cFos eMobility Network","og_description":"Hallo, nach Installation meiner PV-Anlage habe ich mir im Z\u00e4hlerschrank einen Z\u00e4hler Orno OR-WE-517 zusammen mit dem Universal Modbus Gateway (https:\/\/www.ebay.de\/itm\/154058806297\/) einbauen lassen. Nun w\u00fcrde ich gerne den Z\u00e4hler als Netzbezugsz\u00e4hler in der Wallbox einrichten, bekomme das aber nicht hin bzw. es gibt nur den Z\u00e4hler OR-WE-516. Damit bekomme ich aber keine Werte bzw. falsche [&hellip;]","og_url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/zaehler-or-we-517-mit-universal-modbus-gateway\/","og_site_name":"cFos eMobility Network","article_modified_time":"2022-02-25T12:38:31+00:00","twitter_card":"summary_large_image","twitter_site":"@cFosEmobility","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/zaehler-or-we-517-mit-universal-modbus-gateway\/","url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/zaehler-or-we-517-mit-universal-modbus-gateway\/","name":"Z\u00e4hler OR-WE-517 mit Universal Modbus Gateway - cFos eMobility Network","isPartOf":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#website"},"datePublished":"2022-02-22T09:34:04+00:00","dateModified":"2022-02-25T12:38:31+00:00","breadcrumb":{"@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/zaehler-or-we-517-mit-universal-modbus-gateway\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfos-emobility.de\/network\/antworten\/zaehler-or-we-517-mit-universal-modbus-gateway\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/zaehler-or-we-517-mit-universal-modbus-gateway\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.cfos-emobility.de\/network\/"},{"@type":"ListItem","position":2,"name":"Fragen","item":"https:\/\/www.cfos-emobility.de\/network\/antworten\/"},{"@type":"ListItem","position":3,"name":"Z\u00e4hler OR-WE-517 mit Universal Modbus Gateway"}]},{"@type":"WebSite","@id":"https:\/\/www.cfos-emobility.de\/network\/#website","url":"https:\/\/www.cfos-emobility.de\/network\/","name":"cFos eMobility Network","description":"Das cFos Power Brain Community Portal","publisher":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfos-emobility.de\/network\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cfos-emobility.de\/network\/#organization","name":"cFos eMobility GmbH","url":"https:\/\/www.cfos-emobility.de\/network\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","contentUrl":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","width":221,"height":80,"caption":"cFos eMobility GmbH"},"image":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/cFosEmobility"]}]}},"_links":{"self":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread\/397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread"}],"about":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/types\/cma_thread"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/users\/18"}],"wp:attachment":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/media?parent=397"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/tags?post=397"},{"taxonomy":"cma_category","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_category?post=397"},{"taxonomy":"cma_difficulty_level","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_difficulty_level?post=397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}