{"id":3556,"date":"2024-07-19T12:41:34","date_gmt":"2024-07-19T10:41:34","guid":{"rendered":"https:\/\/www.cfos-emobility.de\/network\/antworten\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\/"},"modified":"2024-07-22T15:48:46","modified_gmt":"2024-07-22T13:48:46","slug":"doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig","status":"publish","type":"cma_thread","link":"https:\/\/www.cfos-emobility.de\/network\/antworten\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\/","title":{"rendered":"Doch noch Bug bei Laderegeln? \/ Wechsel von 1- auf Mehrphasig"},"content":{"rendered":"<p>Nachdem vorhin alles gut aussah, und auch das Runterschalten auf 1P wunderbar funktioniert hat (1 Phase, Status-Seite sagt 16A mit L1, also effektiv 5.2A), gab&#8217;s beim R\u00fcckschalten dann doch wieder ein Thema &#8230;<br \/>\nnach den eingestellten 2min in denen wieder &gt;6A zur Verf\u00fcgung standen wurde das Laden beendet, die Wallbox hat auf 3P zur\u00fcckgeschaltet, aber in der Statusseite erst nur L1 mit 16A angezeigt &#8230; tats\u00e4chlich ging es aber mit 11kW in&#8217;s Auto. Au\u00dferdem war aus irgend einem Grund in den Einstellungen zum aktuellen Ladevorgang &#8222;Phasenumschaltung&#8220; und &#8222;einphasig&#8220; aktiv (obwohl nicht manuell eingestellt). Nachdem ich das mehrfach versucht habe auszuschalten hat es die Box endlich akzeptiert. Dann stand aber nur &#8222;L1 L2&#8220;, und sie hat soweit runtergeschaltet, da\u00df &#8211; w\u00e4ren es wirklich nur L1 und L2 &#8211; das \u00dcberschu\u00dfladen wieder korrekt gewesen w\u00e4re. Leider war aber auch hier wieder auf allen drei Phasen Leistung, weswegen statt ~5kW mit \u00fcber 7kW geladen wurde. Ich habe dann in der Konfig nochmal eine \u00c4nderung bei der Laderegel vorgenommen (Sonntag abgeschaltet, sonst nix ge\u00e4ndert) und gespeichert, danach erschienen in der Anzeige wieder alle drei Phasen, die Leistung wurde dann wieder korrekt geregelt um keinen Netzbezug vorzunehmen.<br \/>\nIn weiser Voraussicht hatte ich das Debugging schon vorher aktiviert, anbei &#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachdem vorhin alles gut aussah, und auch das Runterschalten auf 1P wunderbar funktioniert hat (1 Phase, Status-Seite sagt 16A mit L1, also effektiv 5.2A), gab&#8217;s beim R\u00fcckschalten dann doch wieder ein Thema &#8230; nach den eingestellten 2min in denen wieder &gt;6A zur Verf\u00fcgung standen wurde das Laden beendet, die Wallbox hat auf 3P zur\u00fcckgeschaltet, aber [&hellip;]<\/p>\n","protected":false},"author":245,"featured_media":0,"template":"","tags":[23,31,37],"cma_category":[2],"cma_difficulty_level":[],"class_list":["post-3556","cma_thread","type-cma_thread","status-publish","hentry","tag-cfos-charging-manager","tag-phasenumschaltung","tag-ueberschussladen","cma_category-cfos-emobility"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Doch noch Bug bei Laderegeln? \/ Wechsel von 1- auf Mehrphasig - cFos eMobility Network<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doch noch Bug bei Laderegeln? \/ Wechsel von 1- auf Mehrphasig - cFos eMobility Network\" \/>\n<meta property=\"og:description\" content=\"Nachdem vorhin alles gut aussah, und auch das Runterschalten auf 1P wunderbar funktioniert hat (1 Phase, Status-Seite sagt 16A mit L1, also effektiv 5.2A), gab&#8217;s beim R\u00fcckschalten dann doch wieder ein Thema &#8230; nach den eingestellten 2min in denen wieder &gt;6A zur Verf\u00fcgung standen wurde das Laden beendet, die Wallbox hat auf 3P zur\u00fcckgeschaltet, aber [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\/\" \/>\n<meta property=\"og:site_name\" content=\"cFos eMobility Network\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T13:48:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cFosEmobility\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\\\/\",\"name\":\"Doch noch Bug bei Laderegeln? \\\/ Wechsel von 1- auf Mehrphasig - cFos eMobility Network\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\"},\"datePublished\":\"2024-07-19T10:41:34+00:00\",\"dateModified\":\"2024-07-22T13:48:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fragen\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Doch noch Bug bei Laderegeln? \\\/ Wechsel von 1- auf Mehrphasig\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"name\":\"cFos eMobility Network\",\"description\":\"Das cFos Power Brain Community Portal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\",\"name\":\"cFos eMobility GmbH\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"width\":221,\"height\":80,\"caption\":\"cFos eMobility GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/cFosEmobility\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Doch noch Bug bei Laderegeln? \/ Wechsel von 1- auf Mehrphasig - cFos eMobility Network","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfos-emobility.de\/network\/antworten\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\/","og_locale":"de_DE","og_type":"article","og_title":"Doch noch Bug bei Laderegeln? \/ Wechsel von 1- auf Mehrphasig - cFos eMobility Network","og_description":"Nachdem vorhin alles gut aussah, und auch das Runterschalten auf 1P wunderbar funktioniert hat (1 Phase, Status-Seite sagt 16A mit L1, also effektiv 5.2A), gab&#8217;s beim R\u00fcckschalten dann doch wieder ein Thema &#8230; nach den eingestellten 2min in denen wieder &gt;6A zur Verf\u00fcgung standen wurde das Laden beendet, die Wallbox hat auf 3P zur\u00fcckgeschaltet, aber [&hellip;]","og_url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\/","og_site_name":"cFos eMobility Network","article_modified_time":"2024-07-22T13:48:46+00:00","twitter_card":"summary_large_image","twitter_site":"@cFosEmobility","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\/","url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\/","name":"Doch noch Bug bei Laderegeln? \/ Wechsel von 1- auf Mehrphasig - cFos eMobility Network","isPartOf":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#website"},"datePublished":"2024-07-19T10:41:34+00:00","dateModified":"2024-07-22T13:48:46+00:00","breadcrumb":{"@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfos-emobility.de\/network\/antworten\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/doch-noch-bug-bei-laderegeln-wechsel-von-1-auf-mehrphasig\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.cfos-emobility.de\/network\/"},{"@type":"ListItem","position":2,"name":"Fragen","item":"https:\/\/www.cfos-emobility.de\/network\/antworten\/"},{"@type":"ListItem","position":3,"name":"Doch noch Bug bei Laderegeln? \/ Wechsel von 1- auf Mehrphasig"}]},{"@type":"WebSite","@id":"https:\/\/www.cfos-emobility.de\/network\/#website","url":"https:\/\/www.cfos-emobility.de\/network\/","name":"cFos eMobility Network","description":"Das cFos Power Brain Community Portal","publisher":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfos-emobility.de\/network\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cfos-emobility.de\/network\/#organization","name":"cFos eMobility GmbH","url":"https:\/\/www.cfos-emobility.de\/network\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","contentUrl":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","width":221,"height":80,"caption":"cFos eMobility GmbH"},"image":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/cFosEmobility"]}]}},"_links":{"self":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread\/3556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread"}],"about":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/types\/cma_thread"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/users\/245"}],"wp:attachment":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/media?parent=3556"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/tags?post=3556"},{"taxonomy":"cma_category","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_category?post=3556"},{"taxonomy":"cma_difficulty_level","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_difficulty_level?post=3556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}