{"id":1019,"date":"2023-01-16T11:51:12","date_gmt":"2023-01-16T10:51:12","guid":{"rendered":"https:\/\/www.cfos-emobility.de\/network\/antworten\/installationen-mit-batteriespeichern-gesucht\/"},"modified":"2023-02-27T09:34:49","modified_gmt":"2023-02-27T08:34:49","slug":"installationen-mit-batteriespeichern-gesucht","status":"publish","type":"cma_thread","link":"https:\/\/www.cfos-emobility.de\/network\/antworten\/installationen-mit-batteriespeichern-gesucht\/","title":{"rendered":"Installationen mit Batteriespeichern gesucht"},"content":{"rendered":"<p>Hi all,<\/p>\n<p>wir planen die Unterst\u00fctzung von Batteriespeichern im Charging Manager zu verbessern. Hat jemand einen Speicher, der mittels Modbus, HTTP oder auch nur mit Schalteingang steuerbar ist und hat Lust zu experimentieren? Wenn ja, bitte bei unserem Support melden. Das w\u00e4re sehr hilfreich! \ud83d\ude42 #diebestenuserderwelt<\/p>\n<p>Gebt das gerne im Netz weiter, wenn Ihr Kandidaten kennt!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hi all, wir planen die Unterst\u00fctzung von Batteriespeichern im Charging Manager zu verbessern. Hat jemand einen Speicher, der mittels Modbus, HTTP oder auch nur mit Schalteingang steuerbar ist und hat Lust zu experimentieren? Wenn ja, bitte bei unserem Support melden. Das w\u00e4re sehr hilfreich! \ud83d\ude42 #diebestenuserderwelt Gebt das gerne im Netz weiter, wenn Ihr Kandidaten [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"template":"","tags":[101],"cma_category":[],"cma_difficulty_level":[],"class_list":["post-1019","cma_thread","type-cma_thread","status-publish","hentry","tag-batteriespeicher"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Installationen mit Batteriespeichern gesucht - cFos eMobility Network<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/installationen-mit-batteriespeichern-gesucht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Installationen mit Batteriespeichern gesucht - cFos eMobility Network\" \/>\n<meta property=\"og:description\" content=\"Hi all, wir planen die Unterst\u00fctzung von Batteriespeichern im Charging Manager zu verbessern. Hat jemand einen Speicher, der mittels Modbus, HTTP oder auch nur mit Schalteingang steuerbar ist und hat Lust zu experimentieren? Wenn ja, bitte bei unserem Support melden. Das w\u00e4re sehr hilfreich! \ud83d\ude42 #diebestenuserderwelt Gebt das gerne im Netz weiter, wenn Ihr Kandidaten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfos-emobility.de\/network\/antworten\/installationen-mit-batteriespeichern-gesucht\/\" \/>\n<meta property=\"og:site_name\" content=\"cFos eMobility Network\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T08:34:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cFosEmobility\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/installationen-mit-batteriespeichern-gesucht\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/installationen-mit-batteriespeichern-gesucht\\\/\",\"name\":\"Installationen mit Batteriespeichern gesucht - cFos eMobility Network\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\"},\"datePublished\":\"2023-01-16T10:51:12+00:00\",\"dateModified\":\"2023-02-27T08:34:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/installationen-mit-batteriespeichern-gesucht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/installationen-mit-batteriespeichern-gesucht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/installationen-mit-batteriespeichern-gesucht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fragen\",\"item\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/antworten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Installationen mit Batteriespeichern gesucht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#website\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"name\":\"cFos eMobility Network\",\"description\":\"Das cFos Power Brain Community Portal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#organization\",\"name\":\"cFos eMobility GmbH\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cfos-emobility-logo.jpg\",\"width\":221,\"height\":80,\"caption\":\"cFos eMobility GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfos-emobility.de\\\/network\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/cFosEmobility\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Installationen mit Batteriespeichern gesucht - cFos eMobility Network","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfos-emobility.de\/network\/antworten\/installationen-mit-batteriespeichern-gesucht\/","og_locale":"de_DE","og_type":"article","og_title":"Installationen mit Batteriespeichern gesucht - cFos eMobility Network","og_description":"Hi all, wir planen die Unterst\u00fctzung von Batteriespeichern im Charging Manager zu verbessern. Hat jemand einen Speicher, der mittels Modbus, HTTP oder auch nur mit Schalteingang steuerbar ist und hat Lust zu experimentieren? Wenn ja, bitte bei unserem Support melden. Das w\u00e4re sehr hilfreich! \ud83d\ude42 #diebestenuserderwelt Gebt das gerne im Netz weiter, wenn Ihr Kandidaten [&hellip;]","og_url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/installationen-mit-batteriespeichern-gesucht\/","og_site_name":"cFos eMobility Network","article_modified_time":"2023-02-27T08:34:49+00:00","twitter_card":"summary_large_image","twitter_site":"@cFosEmobility","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/installationen-mit-batteriespeichern-gesucht\/","url":"https:\/\/www.cfos-emobility.de\/network\/antworten\/installationen-mit-batteriespeichern-gesucht\/","name":"Installationen mit Batteriespeichern gesucht - cFos eMobility Network","isPartOf":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#website"},"datePublished":"2023-01-16T10:51:12+00:00","dateModified":"2023-02-27T08:34:49+00:00","breadcrumb":{"@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/installationen-mit-batteriespeichern-gesucht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfos-emobility.de\/network\/antworten\/installationen-mit-batteriespeichern-gesucht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfos-emobility.de\/network\/antworten\/installationen-mit-batteriespeichern-gesucht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.cfos-emobility.de\/network\/"},{"@type":"ListItem","position":2,"name":"Fragen","item":"https:\/\/www.cfos-emobility.de\/network\/antworten\/"},{"@type":"ListItem","position":3,"name":"Installationen mit Batteriespeichern gesucht"}]},{"@type":"WebSite","@id":"https:\/\/www.cfos-emobility.de\/network\/#website","url":"https:\/\/www.cfos-emobility.de\/network\/","name":"cFos eMobility Network","description":"Das cFos Power Brain Community Portal","publisher":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfos-emobility.de\/network\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cfos-emobility.de\/network\/#organization","name":"cFos eMobility GmbH","url":"https:\/\/www.cfos-emobility.de\/network\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","contentUrl":"https:\/\/www.cfos-emobility.de\/network\/wp-content\/uploads\/2021\/12\/cfos-emobility-logo.jpg","width":221,"height":80,"caption":"cFos eMobility GmbH"},"image":{"@id":"https:\/\/www.cfos-emobility.de\/network\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/cFosEmobility"]}]}},"_links":{"self":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread\/1019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_thread"}],"about":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/types\/cma_thread"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/users\/19"}],"wp:attachment":[{"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/media?parent=1019"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/tags?post=1019"},{"taxonomy":"cma_category","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_category?post=1019"},{"taxonomy":"cma_difficulty_level","embeddable":true,"href":"https:\/\/www.cfos-emobility.de\/network\/wp-json\/wp\/v2\/cma_difficulty_level?post=1019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}